{"id":16998,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/fr\/attrazioni\/tomba-di-giganti-sas-de-mattu-ii-oliena\/","name":"Tomba di Giganti sas de Mattu II","slug":"tomba-di-giganti-sas-de-mattu-ii-oliena","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni\/16998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/tour?attrazioni=16998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}