{"id":15447,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/fr\/attrazioni\/tomba-di-giganti-san-giacomo-siniscola\/","name":"Tomba di Giganti San Giacomo","slug":"tomba-di-giganti-san-giacomo-siniscola","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni\/15447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/tour?attrazioni=15447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}