{"id":13716,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/fr\/attrazioni\/tuones-viewpoint-oliena\/","name":"Tuones Viewpoint","slug":"tuones-viewpoint-oliena","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni\/13716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/tour?attrazioni=13716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}