{"id":13210,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/fr\/attrazioni\/statua-del-cristo-di-monte-tuttavista-galtelli\/","name":"Statua del Cristo di Monte Tuttavista","slug":"statua-del-cristo-di-monte-tuttavista-galtelli","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni\/13210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/tour?attrazioni=13210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}