{"id":13173,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/fr\/attrazioni\/scoglio-dell-indiano-la-maddalena\/","name":"Scoglio dell'indiano","slug":"scoglio-dell-indiano-la-maddalena","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni\/13173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/fr\/wp-json\/wp\/v2\/tour?attrazioni=13173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}