{"id":17836,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/es\/attrazioni\/sa-tellura-domusnovas\/","name":"Sa Tellura","slug":"sa-tellura-domusnovas","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni\/17836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/tour?attrazioni=17836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}