{"id":15912,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/es\/attrazioni\/resti-di-colonne-ioniche-pula\/","name":"Resti di colonne ioniche","slug":"resti-di-colonne-ioniche-pula","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni\/15912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/tour?attrazioni=15912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}