{"id":12502,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/es\/attrazioni\/sa-duchessa-domusnovas\/","name":"Sa Duchessa","slug":"sa-duchessa-domusnovas","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni\/12502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/tour?attrazioni=12502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}