{"id":11885,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/es\/attrazioni\/ponte-papaloppe-oliena\/","name":"Ponte Papaloppe","slug":"ponte-papaloppe-oliena","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni\/11885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/tour?attrazioni=11885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}