{"id":10668,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/es\/attrazioni\/cala-sapone-sant-antioco\/","name":"Cala Jab\u00f3n","slug":"cala-sapone-sant-antioco","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni\/10668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/es\/wp-json\/wp\/v2\/tour?attrazioni=10668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}