{"id":18324,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/en\/attrazioni\/pendolo-di-foucault-monserrato\/","name":"Pendolo di Foucault","slug":"pendolo-di-foucault-monserrato","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni\/18324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/tour?attrazioni=18324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}