{"id":15880,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/en\/attrazioni\/nuraghe-mitza-sa-granaccia-costa-rei\/","name":"Nuraghe Mitza sa Granaccia","slug":"nuraghe-mitza-sa-granaccia-costa-rei","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni\/15880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/tour?attrazioni=15880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}