{"id":15727,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/en\/attrazioni\/bivio-delle-martore-capoterra\/","name":"Bivio delle Martore","slug":"bivio-delle-martore-capoterra","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni\/15727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/tour?attrazioni=15727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}