{"id":15502,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/en\/attrazioni\/statua-falcone-e-borsellino-sestu\/","name":"Statua Falcone e Borsellino","slug":"statua-falcone-e-borsellino-sestu","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni\/15502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/tour?attrazioni=15502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}