{"id":12142,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/en\/attrazioni\/dune-di-torre-dei-corsari-arbus\/","name":"Dune di Torre dei Corsari","slug":"dune-di-torre-dei-corsari-arbus","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni\/12142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/en\/wp-json\/wp\/v2\/tour?attrazioni=12142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}