{"id":6640,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/citta\/valledoria\/","name":"Valledoria","slug":"valledoria","taxonomy":"citta","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/citta\/6640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/citta"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/citta"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?citta=6640"},{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/accommodation?citta=6640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}