{"id":18080,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/tomba-dei-giganti-talanuse-aritzo\/","name":"Tomba dei giganti Talanus\u00e8","slug":"tomba-dei-giganti-talanuse-aritzo","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/18080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=18080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}