{"id":17577,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/terme-di-s-acqua-cotta-villasor\/","name":"Terme di S'Acqua Cotta","slug":"terme-di-s-acqua-cotta-villasor","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/17577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=17577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}