{"id":17572,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/pozzo-sacro-sa-matta-de-s-ollastu-villasor\/","name":"Pozzo Sacro Sa Matta de s'Ollastu","slug":"pozzo-sacro-sa-matta-de-s-ollastu-villasor","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/17572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=17572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}