{"id":14675,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/monte-gennargentu-desulo\/","name":"Monte Gennargentu","slug":"monte-gennargentu-desulo","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/14675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=14675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}