{"id":12944,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/belvedere-di-monte-murone-alghero\/","name":"Belvedere di Monte Murone","slug":"belvedere-di-monte-murone-alghero","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/12944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=12944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}