{"id":12134,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/miniera-di-ingurtosu-pozzo-gal-museo-multimediale-della-miniera-arbus\/","name":"Miniera di Ingurtosu - Pozzo Gal - Museo Multimediale della miniera","slug":"miniera-di-ingurtosu-pozzo-gal-museo-multimediale-della-miniera-arbus","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/12134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=12134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}