{"id":11962,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/cascate-di-lequarci-ulassai\/","name":"Cascate di Lequarci","slug":"cascate-di-lequarci-ulassai","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/11962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=11962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}