{"id":10595,"count":0,"description":"","link":"https:\/\/www.yepsea.com\/de\/attrazioni\/parco-territoriale-e-urbano-della-pineta-di-sinnai-sinnai\/","name":"Parco Territoriale e Urbano della Pineta di Sinnai","slug":"parco-territoriale-e-urbano-della-pineta-di-sinnai-sinnai","taxonomy":"attrazioni","meta":[],"_links":{"self":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni\/10595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/attrazioni"}],"about":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/taxonomies\/attrazioni"}],"wp:post_type":[{"href":"https:\/\/www.yepsea.com\/de\/wp-json\/wp\/v2\/tour?attrazioni=10595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}